{"id":27567,"date":"2021-01-27T17:06:31","date_gmt":"2021-01-27T17:06:31","guid":{"rendered":"https:\/\/www.jamalfi.bio\/?p=27567"},"modified":"2021-09-20T10:34:13","modified_gmt":"2021-09-20T09:34:13","slug":"a-san-valentino-regala-la-bellezza","status":"publish","type":"post","link":"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/","title":{"rendered":"A San Valentino regala la bellezza"},"content":{"rendered":"<p style=\"text-align: center;\">A San Valentino fai un regalo di bellezza!<\/p>\n<p style=\"text-align: center;\">Approfitta della nostra promozione del 10% su tutti i prodotti, utilizzando il coupon <strong>AMORE10.\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a class=\"btn\" href=\"https:\/\/www.jamalfi.bio\/shop\/\">VAI ALLO SHOP<\/a><\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>&#8230;<\/p>\n","protected":false},"author":8,"featured_media":26046,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A San Valentino regala la bellezza - Jamalfi Biocosmetics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A San Valentino regala la bellezza - Jamalfi Biocosmetics\" \/>\n<meta property=\"og:description\" content=\"...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/\" \/>\n<meta property=\"og:site_name\" content=\"Jamalfi Biocosmetics\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/Jamalfibiocosmetics\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-27T17:06:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-20T09:34:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jamalfi.bio\/wp-content\/uploads\/2019\/10\/Jamalfi-Organic-Skincare-for-face-and-body-850x566-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"566\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Amalfi Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amalfi Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/\",\"url\":\"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/\",\"name\":\"A San Valentino regala la bellezza - Jamalfi Biocosmetics\",\"isPartOf\":{\"@id\":\"https:\/\/www.jamalfi.bio\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.jamalfi.bio\/wp-content\/uploads\/2019\/10\/Jamalfi-Organic-Skincare-for-face-and-body-850x566-1.jpg\",\"datePublished\":\"2021-01-27T17:06:31+00:00\",\"dateModified\":\"2021-09-20T09:34:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.jamalfi.bio\/it\/#\/schema\/person\/4412d89747892b5752e92fdab83f82d2\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/#primaryimage\",\"url\":\"https:\/\/www.jamalfi.bio\/wp-content\/uploads\/2019\/10\/Jamalfi-Organic-Skincare-for-face-and-body-850x566-1.jpg\",\"contentUrl\":\"https:\/\/www.jamalfi.bio\/wp-content\/uploads\/2019\/10\/Jamalfi-Organic-Skincare-for-face-and-body-850x566-1.jpg\",\"width\":850,\"height\":566},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.jamalfi.bio\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A San Valentino regala la bellezza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.jamalfi.bio\/it\/#website\",\"url\":\"https:\/\/www.jamalfi.bio\/it\/\",\"name\":\"Jamalfi Biocosmetics\",\"description\":\"Beauty Rituals from Amalfi Coast\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.jamalfi.bio\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.jamalfi.bio\/it\/#\/schema\/person\/4412d89747892b5752e92fdab83f82d2\",\"name\":\"Amalfi Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.jamalfi.bio\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8b28bb2ab53b523d94cf5079384e06e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8b28bb2ab53b523d94cf5079384e06e6?s=96&d=mm&r=g\",\"caption\":\"Amalfi Web\"},\"sameAs\":[\"https:\/\/www.amalfiweb.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A San Valentino regala la bellezza - Jamalfi Biocosmetics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/","og_locale":"en_US","og_type":"article","og_title":"A San Valentino regala la bellezza - Jamalfi Biocosmetics","og_description":"...","og_url":"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/","og_site_name":"Jamalfi Biocosmetics","article_publisher":"http:\/\/www.facebook.com\/Jamalfibiocosmetics\/","article_published_time":"2021-01-27T17:06:31+00:00","article_modified_time":"2021-09-20T09:34:13+00:00","og_image":[{"width":850,"height":566,"url":"https:\/\/www.jamalfi.bio\/wp-content\/uploads\/2019\/10\/Jamalfi-Organic-Skincare-for-face-and-body-850x566-1.jpg","type":"image\/jpeg"}],"author":"Amalfi Web","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Amalfi Web","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/","url":"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/","name":"A San Valentino regala la bellezza - Jamalfi Biocosmetics","isPartOf":{"@id":"https:\/\/www.jamalfi.bio\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/#primaryimage"},"image":{"@id":"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jamalfi.bio\/wp-content\/uploads\/2019\/10\/Jamalfi-Organic-Skincare-for-face-and-body-850x566-1.jpg","datePublished":"2021-01-27T17:06:31+00:00","dateModified":"2021-09-20T09:34:13+00:00","author":{"@id":"https:\/\/www.jamalfi.bio\/it\/#\/schema\/person\/4412d89747892b5752e92fdab83f82d2"},"breadcrumb":{"@id":"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/#primaryimage","url":"https:\/\/www.jamalfi.bio\/wp-content\/uploads\/2019\/10\/Jamalfi-Organic-Skincare-for-face-and-body-850x566-1.jpg","contentUrl":"https:\/\/www.jamalfi.bio\/wp-content\/uploads\/2019\/10\/Jamalfi-Organic-Skincare-for-face-and-body-850x566-1.jpg","width":850,"height":566},{"@type":"BreadcrumbList","@id":"https:\/\/www.jamalfi.bio\/en\/a-san-valentino-regala-la-bellezza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jamalfi.bio\/en\/"},{"@type":"ListItem","position":2,"name":"A San Valentino regala la bellezza"}]},{"@type":"WebSite","@id":"https:\/\/www.jamalfi.bio\/it\/#website","url":"https:\/\/www.jamalfi.bio\/it\/","name":"Jamalfi Biocosmetics","description":"Beauty Rituals from Amalfi Coast","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jamalfi.bio\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.jamalfi.bio\/it\/#\/schema\/person\/4412d89747892b5752e92fdab83f82d2","name":"Amalfi Web","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.jamalfi.bio\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8b28bb2ab53b523d94cf5079384e06e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b28bb2ab53b523d94cf5079384e06e6?s=96&d=mm&r=g","caption":"Amalfi Web"},"sameAs":["https:\/\/www.amalfiweb.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.jamalfi.bio\/en\/wp-json\/wp\/v2\/posts\/27567"}],"collection":[{"href":"https:\/\/www.jamalfi.bio\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jamalfi.bio\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jamalfi.bio\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jamalfi.bio\/en\/wp-json\/wp\/v2\/comments?post=27567"}],"version-history":[{"count":0,"href":"https:\/\/www.jamalfi.bio\/en\/wp-json\/wp\/v2\/posts\/27567\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jamalfi.bio\/en\/wp-json\/wp\/v2\/media\/26046"}],"wp:attachment":[{"href":"https:\/\/www.jamalfi.bio\/en\/wp-json\/wp\/v2\/media?parent=27567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jamalfi.bio\/en\/wp-json\/wp\/v2\/categories?post=27567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jamalfi.bio\/en\/wp-json\/wp\/v2\/tags?post=27567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}